{"id":3560,"date":"2021-01-05T13:51:28","date_gmt":"2021-01-05T12:51:28","guid":{"rendered":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/?p=3560"},"modified":"2021-03-03T10:51:26","modified_gmt":"2021-03-03T09:51:26","slug":"choose-africa-takes-a-new-step","status":"publish","type":"post","link":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/","title":{"rendered":"Choose Africa takes a new step"},"content":{"rendered":"<style type=\"text\/css\">\nbody {overflow: hidden;}main {\tmax-width: 100%; margin: 0 auto;padding: 0;}.titreactureportage,.back,.headercontainer,.subheader,.sharifftext,.shariff,.post-edit-link,.footer{display: none!important;}.cnt {width: 100%;position: absolute;\theight: 75vh;z-index: 9;}<br \/>@media all and (max-width: 970px){.cnt {height: 82vh;}}<\/style>\n<div class=\"cnt\"><iframe loading=\"lazy\" class=\"frm\" style=\"overflow: visible;\" src=\"https:\/\/www.animalpensant.com\/choose-africa-proparco\/en\/\" width=\"100%\" height=\"100%\" frameborder=\"0\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":3557,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71],"tags":[],"pays":[],"offres":[],"class_list":["post-3560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Choose Africa takes a new step - Choose Africa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Choose Africa takes a new step - Choose Africa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\" \/>\n<meta property=\"og:site_name\" content=\"Choose Africa\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-05T12:51:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-03T09:51:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"489\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"francois hirsch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"francois hirsch\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\"},\"author\":{\"name\":\"francois hirsch\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/58210e1fe42867e8f4049751b9ae886c\"},\"headline\":\"Choose Africa takes a new step\",\"datePublished\":\"2021-01-05T12:51:28+00:00\",\"dateModified\":\"2021-03-03T09:51:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\"},\"wordCount\":6,\"publisher\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization\"},\"image\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\",\"url\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\",\"name\":\"Choose Africa takes a new step - Choose Africa\",\"isPartOf\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg\",\"datePublished\":\"2021-01-05T12:51:28+00:00\",\"dateModified\":\"2021-03-03T09:51:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage\",\"url\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg\",\"contentUrl\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg\",\"width\":1170,\"height\":489},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Choose Africa takes a new step\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#website\",\"url\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/\",\"name\":\"Choose Africa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization\",\"name\":\"Choose Africa\",\"url\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2019\/03\/CHOOSE-AFRICA.png\",\"contentUrl\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2019\/03\/CHOOSE-AFRICA.png\",\"width\":600,\"height\":256,\"caption\":\"Choose Africa\"},\"image\":{\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/58210e1fe42867e8f4049751b9ae886c\",\"name\":\"francois hirsch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9b5b33e88b190c77b22b0cf763ed0aa9c46ab12b54b296ea58ac04555a2e78ac?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9b5b33e88b190c77b22b0cf763ed0aa9c46ab12b54b296ea58ac04555a2e78ac?s=96&d=mm&r=g\",\"caption\":\"francois hirsch\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Choose Africa takes a new step - Choose Africa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/","og_locale":"en_US","og_type":"article","og_title":"Choose Africa takes a new step - Choose Africa","og_url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/","og_site_name":"Choose Africa","article_published_time":"2021-01-05T12:51:28+00:00","article_modified_time":"2021-03-03T09:51:26+00:00","og_image":[{"width":1170,"height":489,"url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg","type":"image\/jpeg"}],"author":"francois hirsch","twitter_card":"summary_large_image","twitter_misc":{"Written by":"francois hirsch"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#article","isPartOf":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/"},"author":{"name":"francois hirsch","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/58210e1fe42867e8f4049751b9ae886c"},"headline":"Choose Africa takes a new step","datePublished":"2021-01-05T12:51:28+00:00","dateModified":"2021-03-03T09:51:26+00:00","mainEntityOfPage":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/"},"wordCount":6,"publisher":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization"},"image":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage"},"thumbnailUrl":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg","articleSection":["News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/","url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/","name":"Choose Africa takes a new step - Choose Africa","isPartOf":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#website"},"primaryImageOfPage":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage"},"image":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage"},"thumbnailUrl":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg","datePublished":"2021-01-05T12:51:28+00:00","dateModified":"2021-03-03T09:51:26+00:00","breadcrumb":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#primaryimage","url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg","contentUrl":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2021\/01\/capuc.jpg","width":1170,"height":489},{"@type":"BreadcrumbList","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/news\/choose-africa-takes-a-new-step\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/"},{"@type":"ListItem","position":2,"name":"Choose Africa takes a new step"}]},{"@type":"WebSite","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#website","url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/","name":"Choose Africa","description":"","publisher":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#organization","name":"Choose Africa","url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/logo\/image\/","url":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2019\/03\/CHOOSE-AFRICA.png","contentUrl":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/wp-content\/uploads\/2019\/03\/CHOOSE-AFRICA.png","width":600,"height":256,"caption":"Choose Africa"},"image":{"@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/58210e1fe42867e8f4049751b9ae886c","name":"francois hirsch","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9b5b33e88b190c77b22b0cf763ed0aa9c46ab12b54b296ea58ac04555a2e78ac?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9b5b33e88b190c77b22b0cf763ed0aa9c46ab12b54b296ea58ac04555a2e78ac?s=96&d=mm&r=g","caption":"francois hirsch"}}]}},"_links":{"self":[{"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/posts\/3560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/comments?post=3560"}],"version-history":[{"count":0,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/posts\/3560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/media\/3557"}],"wp:attachment":[{"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/media?parent=3560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/categories?post=3560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/tags?post=3560"},{"taxonomy":"pays","embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/pays?post=3560"},{"taxonomy":"offres","embeddable":true,"href":"https:\/\/afd-chooseafrica-qa.cegedim.cloud\/en\/wp-json\/wp\/v2\/offres?post=3560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}